{"id":3153,"date":"2016-01-26T23:56:13","date_gmt":"2016-01-26T21:56:13","guid":{"rendered":"https:\/\/fivlleida.cat\/?page_id=3153&#038;lang=es"},"modified":"2024-08-12T22:48:50","modified_gmt":"2024-08-12T20:48:50","slug":"contactar","status":"publish","type":"page","link":"https:\/\/fivlleida.cat\/es\/contactar\/","title":{"rendered":"Contactar"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row el_position=\u00bbfirst\u00bb][vc_column][vc_column_text]<iframe loading=\"lazy\" style=\"border: 0;\" src=\"https:\/\/www.google.com\/maps\/embed?pb=!1m18!1m12!1m3!1d2982.9270671986164!2d0.6163474771671615!3d41.61408878190105!2m3!1f0!2f0!3f0!3m2!1i1024!2i768!4f13.1!3m3!1m2!1s0x12a6e0136421386f%3A0x2a38096afd71313c!2sFIV%20Lleida!5e0!3m2!1ses!2ses!4v1723477170866!5m2!1ses!2ses\" width=\"100%\" height=\"300\" allowfullscreen=\"allowfullscreen\"><\/iframe>[\/vc_column_text][\/vc_column][\/vc_row][vc_row top_margin=\u00bbpage_margin_top_section\u00bb el_position=\u00bblast\u00bb][vc_column width=\u00bb2\/3&#8243;]<h3 class=\"box-header animation-slide\">Cons\u00faltenos<\/h3>[vc_column_text css=\u00bb\u00bb]<style id=\"wpforms-css-vars-6139\">\n\t\t\t\t#wpforms-6139 {\n\t\t\t\t\n\t\t\t}\n\t\t\t<\/style><div class=\"wpforms-container wpforms-container-full formulari-fivlleida wpforms-render-modern\" id=\"wpforms-6139\"><form id=\"wpforms-form-6139\" class=\"wpforms-validate wpforms-form wpforms-ajax-form\" data-formid=\"6139\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/es\/wp-json\/wp\/v2\/pages\/3153\" data-token=\"cc2398dc676bee7d867f27b2344465ef\" data-token-time=\"1784159808\"><noscript class=\"wpforms-error-noscript\">Por favor, activa JavaScript en tu navegador para completar este formulario.<\/noscript><div id=\"wpforms-error-noscript\" style=\"display: none;\">Por favor, activa JavaScript en tu navegador para completar este formulario.<\/div><div class=\"wpforms-field-container\"><div id=\"wpforms-6139-field_3-container\" class=\"wpforms-field wpforms-field-text wpforms-one-half wpforms-first\" data-field-id=\"3\"><label class=\"wpforms-field-label\" for=\"wpforms-6139-field_3\">Nombre y apellidos <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-6139-field_3\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][3]\" aria-errormessage=\"wpforms-6139-field_3-error\" required><\/div><div id=\"wpforms-6139-field_1-container\" class=\"wpforms-field wpforms-field-email wpforms-one-half\" data-field-id=\"1\"><label class=\"wpforms-field-label\" for=\"wpforms-6139-field_1\">E-mail <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"email\" id=\"wpforms-6139-field_1\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][1]\" spellcheck=\"false\" aria-errormessage=\"wpforms-6139-field_1-error\" required><\/div><div id=\"wpforms-6139-field_6-container\" class=\"wpforms-field wpforms-field-select wpforms-field-select-style-classic\" data-field-id=\"6\"><label class=\"wpforms-field-label\" for=\"wpforms-6139-field_6\">Selecciona una opci\u00f3n <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><select id=\"wpforms-6139-field_6\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][6]\" required=\"required\"><option value=\"Informaci\u00f3n general\"  class=\"choice-1 depth-1\"  >Informaci\u00f3n general<\/option><option value=\"Donaci\u00f3n de semen\"  class=\"choice-2 depth-1\"  >Donaci\u00f3n de semen<\/option><option value=\"Donaci\u00f3n de \u00f3vulos\"  class=\"choice-3 depth-1\"  >Donaci\u00f3n de \u00f3vulos<\/option><\/select><\/div><div id=\"wpforms-6139-field_2-container\" class=\"wpforms-field wpforms-field-textarea\" data-field-id=\"2\"><label class=\"wpforms-field-label\" for=\"wpforms-6139-field_2\">Missatge <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><textarea id=\"wpforms-6139-field_2\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][2]\" aria-errormessage=\"wpforms-6139-field_2-error\" required><\/textarea><\/div><div id=\"wpforms-6139-field_7-container\" class=\"wpforms-field wpforms-field-checkbox textpetit\" data-field-id=\"7\"><fieldset><legend class=\"wpforms-field-label wpforms-label-hide\" aria-hidden=\"false\">ProteccioDades <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/legend><ul id=\"wpforms-6139-field_7\" class=\"wpforms-field-required\"><li class=\"choice-3 depth-1\"><input type=\"checkbox\" id=\"wpforms-6139-field_7_3\" name=\"wpforms[fields][7][]\" value=\"Acepto que mis datos sean tratados por Centre d&#039;infertilitat i reproducci\u00f3  humana de Lleida, S.L. para la gesti\u00f3n del servicio.\" aria-errormessage=\"wpforms-6139-field_7_3-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-6139-field_7_3\">Acepto que mis datos sean tratados por Centre d'infertilitat i reproducci\u00f3  humana de Lleida, S.L. para la gesti\u00f3n del servicio.<\/label><\/li><\/ul><\/fieldset><\/div><div id=\"wpforms-6139-field_8-container\" class=\"wpforms-field wpforms-field-checkbox textpetit\" data-field-id=\"8\"><fieldset><legend class=\"wpforms-field-label wpforms-label-hide\" aria-hidden=\"false\">AcceptacioPubli<\/legend><ul id=\"wpforms-6139-field_8\"><li class=\"choice-3 depth-1\"><input type=\"checkbox\" id=\"wpforms-6139-field_8_3\" name=\"wpforms[fields][8][]\" value=\"Acepto que Centre d&#039;infertilitat i reproducci\u00f3  humana de Lleida, S.L. me env\u00ede informaci\u00f3n comercial.\" aria-errormessage=\"wpforms-6139-field_8_3-error\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-6139-field_8_3\">Acepto que Centre d'infertilitat i reproducci\u00f3  humana de Lleida, S.L. me env\u00ede informaci\u00f3n comercial.<\/label><\/li><\/ul><\/fieldset><\/div><\/div><!-- .wpforms-field-container --><div class=\"wpforms-recaptcha-container wpforms-is-recaptcha wpforms-is-recaptcha-type-v3\" ><input type=\"hidden\" name=\"wpforms[recaptcha]\" value=\"\"><\/div><div class=\"wpforms-submit-container\" ><input type=\"hidden\" name=\"wpforms[id]\" value=\"6139\"><input type=\"hidden\" name=\"page_title\" value=\"\"><input type=\"hidden\" name=\"page_url\" value=\"https:\/\/fivlleida.cat\/es\/wp-json\/wp\/v2\/pages\/3153\"><input type=\"hidden\" name=\"url_referer\" value=\"\"><button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-6139\" class=\"wpforms-submit\" data-alt-text=\"Se est\u00e1 enviando...\" data-submit-text=\"Envia\" aria-live=\"assertive\" value=\"wpforms-submit\">Envia<\/button><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/fivlleida.cat\/wp-content\/plugins\/wpforms-lite\/assets\/images\/submit-spin.svg\" class=\"wpforms-submit-spinner\" style=\"display: none;\" width=\"26\" height=\"26\" alt=\"Cargando\"><\/div><\/form><\/div>  <!-- .wpforms-container -->[\/vc_column_text][vc_empty_space][vc_empty_space][vc_column_text]<span style=\"font-size: 10px;\"><strong>Nota Legal:<\/strong><br \/>\nCentre d&#8217;infertilitat i reproducci\u00f3 humana de Lleida, S.L. es el responsable de tratamiento de los datos de car\u00e1cter personal contenidos en este documento.<br \/>\n<strong>Finalidad:<\/strong> Tratamos la informaci\u00f3n que nos facilita con el fin de prestar el servicio solicitado, realizar la facturaci\u00f3n y el cobro del mismo.<br \/>\n<strong>Legitimaci\u00f3n:<\/strong> Relaci\u00f3n contractual.<br \/>\n<strong>Plazo de conservaci\u00f3n de los datos:<\/strong> Los datos proporcionados se conservar\u00e1n mientras se mantenga la relaci\u00f3n comercial o durante los a\u00f1os necesarios para cumplir con las obligaciones legales.<br \/>\n<strong>Destinatarios:<\/strong> Los datos no se ceder\u00e1n a terceros salvo en los casos en que exista una obligaci\u00f3n legal.<br \/>\n<strong>Derechos:<\/strong> Podr\u00e1 ejercer sus derechos de acceso, rectificaci\u00f3n, limitaci\u00f3n y supresi\u00f3n dirigi\u00e9ndose por escrito a Calle Alcalde Sol, N.4, 25003, LLEIDA, LLEIDA o por correo electr\u00f3nico a <a href=\"mailto:info@fivlleida.cat\">info@fivlleida.cat<\/a>.<br \/>\n<strong>Informaci\u00f3n adicional:<\/strong> Puede consultar la informaci\u00f3n adicional y detallada sobre Protecci\u00f3n de Datos en nuestra p\u00e1gina web: <a href=\"https:\/\/fivlleida.cat\/proteccio-de-dades\/\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/fivlleida.cat\/proteccio-de-dades\/<\/a><\/span>[\/vc_column_text][\/vc_column][vc_column width=\u00bb1\/3&#8243;][vc_widget_sidebar sidebar_id=\u00bbsidebar-home-right-style-2&#8243; el_position=\u00bbfirst last\u00bb][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row el_position=\u00bbfirst\u00bb][vc_column][vc_column_text][\/vc_column_text][\/vc_column][\/vc_row][vc_row top_margin=\u00bbpage_margin_top_section\u00bb el_position=\u00bblast\u00bb][vc_column width=\u00bb2\/3&#8243;][vc_column_text css=\u00bb\u00bb][\/vc_column_text][vc_empty_space][vc_empty_space][vc_column_text]Nota Legal: Centre d&#8217;infertilitat i reproducci\u00f3 humana de Lleida, S.L. es el responsable de tratamiento de los datos de car\u00e1cter personal contenidos en este documento. Finalidad: Tratamos la informaci\u00f3n que nos facilita con el fin de prestar el servicio solicitado, realizar la facturaci\u00f3n y el cobro del mismo. Legitimaci\u00f3n: Relaci\u00f3n<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"open","ping_status":"open","template":"","meta":{"footnotes":""},"class_list":["post-3153","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Contactar - Fivlleida.cat<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fivlleida.cat\/es\/contactar\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Contactar - Fivlleida.cat\" \/>\n<meta property=\"og:description\" content=\"[vc_row el_position=\u00bbfirst\u00bb][vc_column][vc_column_text][\/vc_column_text][\/vc_column][\/vc_row][vc_row top_margin=\u00bbpage_margin_top_section\u00bb el_position=\u00bblast\u00bb][vc_column width=\u00bb2\/3&#8243;][vc_column_text css=\u00bb\u00bb][\/vc_column_text][vc_empty_space][vc_empty_space][vc_column_text]Nota Legal: Centre d&#8217;infertilitat i reproducci\u00f3 humana de Lleida, S.L. es el responsable de tratamiento de los datos de car\u00e1cter personal contenidos en este documento. Finalidad: Tratamos la informaci\u00f3n que nos facilita con el fin de prestar el servicio solicitado, realizar la facturaci\u00f3n y el cobro del mismo. Legitimaci\u00f3n: Relaci\u00f3n\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fivlleida.cat\/es\/contactar\/\" \/>\n<meta property=\"og:site_name\" content=\"Fivlleida.cat\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-12T20:48:50+00:00\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/fivlleida.cat\/es\/contactar\/\",\"url\":\"https:\/\/fivlleida.cat\/es\/contactar\/\",\"name\":\"Contactar - Fivlleida.cat\",\"isPartOf\":{\"@id\":\"https:\/\/fivlleida.cat\/#website\"},\"datePublished\":\"2016-01-26T21:56:13+00:00\",\"dateModified\":\"2024-08-12T20:48:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/fivlleida.cat\/es\/contactar\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/fivlleida.cat\/es\/contactar\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/fivlleida.cat\/es\/contactar\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/fivlleida.cat\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Contactar\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/fivlleida.cat\/#website\",\"url\":\"https:\/\/fivlleida.cat\/\",\"name\":\"Fivlleida.cat\",\"description\":\"Center for Human Reproduction and Infertility Lleida\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/fivlleida.cat\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Contactar - Fivlleida.cat","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fivlleida.cat\/es\/contactar\/","og_locale":"es_ES","og_type":"article","og_title":"Contactar - Fivlleida.cat","og_description":"[vc_row el_position=\u00bbfirst\u00bb][vc_column][vc_column_text][\/vc_column_text][\/vc_column][\/vc_row][vc_row top_margin=\u00bbpage_margin_top_section\u00bb el_position=\u00bblast\u00bb][vc_column width=\u00bb2\/3&#8243;][vc_column_text css=\u00bb\u00bb][\/vc_column_text][vc_empty_space][vc_empty_space][vc_column_text]Nota Legal: Centre d&#8217;infertilitat i reproducci\u00f3 humana de Lleida, S.L. es el responsable de tratamiento de los datos de car\u00e1cter personal contenidos en este documento. Finalidad: Tratamos la informaci\u00f3n que nos facilita con el fin de prestar el servicio solicitado, realizar la facturaci\u00f3n y el cobro del mismo. Legitimaci\u00f3n: Relaci\u00f3n","og_url":"https:\/\/fivlleida.cat\/es\/contactar\/","og_site_name":"Fivlleida.cat","article_modified_time":"2024-08-12T20:48:50+00:00","twitter_misc":{"Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/fivlleida.cat\/es\/contactar\/","url":"https:\/\/fivlleida.cat\/es\/contactar\/","name":"Contactar - Fivlleida.cat","isPartOf":{"@id":"https:\/\/fivlleida.cat\/#website"},"datePublished":"2016-01-26T21:56:13+00:00","dateModified":"2024-08-12T20:48:50+00:00","breadcrumb":{"@id":"https:\/\/fivlleida.cat\/es\/contactar\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fivlleida.cat\/es\/contactar\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/fivlleida.cat\/es\/contactar\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/fivlleida.cat\/es\/"},{"@type":"ListItem","position":2,"name":"Contactar"}]},{"@type":"WebSite","@id":"https:\/\/fivlleida.cat\/#website","url":"https:\/\/fivlleida.cat\/","name":"Fivlleida.cat","description":"Center for Human Reproduction and Infertility Lleida","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fivlleida.cat\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/fivlleida.cat\/es\/wp-json\/wp\/v2\/pages\/3153"}],"collection":[{"href":"https:\/\/fivlleida.cat\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/fivlleida.cat\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/fivlleida.cat\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/fivlleida.cat\/es\/wp-json\/wp\/v2\/comments?post=3153"}],"version-history":[{"count":14,"href":"https:\/\/fivlleida.cat\/es\/wp-json\/wp\/v2\/pages\/3153\/revisions"}],"predecessor-version":[{"id":6145,"href":"https:\/\/fivlleida.cat\/es\/wp-json\/wp\/v2\/pages\/3153\/revisions\/6145"}],"wp:attachment":[{"href":"https:\/\/fivlleida.cat\/es\/wp-json\/wp\/v2\/media?parent=3153"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}